{"id":1176,"date":"2020-07-06T15:02:21","date_gmt":"2020-07-06T13:02:21","guid":{"rendered":"http:\/\/somosusted.com\/naming\/unison\/"},"modified":"2020-08-05T13:11:07","modified_gmt":"2020-08-05T11:11:07","slug":"unison","status":"publish","type":"naming","link":"https:\/\/somosusted.com\/ca\/naming-projects\/unison\/","title":{"rendered":"Unison"},"content":{"rendered":"\n<p>Canviar la ind\u00fastria musical \u00e9s un repte ambici\u00f3s. Aquesta nova companyia de gesti\u00f3 de drets neix per aportar la tecnologia, la transpar\u00e8ncia i l\u2019efici\u00e8ncia que la SGAE no ha aconseguit portar fins ara. <em>Posa d\u2019acord a creadors, editors i consumidors de m\u00fasica<\/em>. Els uneix en una sola causa, una sola veu. Fes un cop d\u2019ull a la resta del projecte que vam fer <span style=\"text-decoration: underline;\"><a href=\"http:\/\/somosusted.com\/ca\/project\/unison\/\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a><\/span>. <\/p>\n","protected":false},"featured_media":0,"menu_order":68,"template":"","class_list":["post-1176","naming","type-naming","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/naming\/1176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/naming"}],"about":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/types\/naming"}],"wp:attachment":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/media?parent=1176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}