{"id":1216,"date":"2020-07-06T14:17:17","date_gmt":"2020-07-06T12:17:17","guid":{"rendered":"http:\/\/somosusted.com\/naming\/casa-volver\/"},"modified":"2020-12-04T13:09:59","modified_gmt":"2020-12-04T11:09:59","slug":"casa-volver","status":"publish","type":"naming","link":"https:\/\/somosusted.com\/ca\/naming-projects\/casa-volver\/","title":{"rendered":"Casa Volver"},"content":{"rendered":"\n<p>Un hotel en un dels millors llocs de Barcelona, la Rambla. Davant de la font de Canaletes, sobre qui la llegenda diu que <em>qui en begui aigua tornar\u00e0 a la ciutat<\/em>. El nom neix d\u2019aquesta hist\u00f2ria tan barcelonina i agafa una forma molt particular, que fa de la ciutat casa teva i et convida a tornar.&nbsp;<\/p>\n\n\n\n<div id=\"gallery-block_5f25a4403e79c\" class=\"gallery-block w-full\">\n\n    \n\n\t\t<div class=\"cursor-carousel relative\">\n\t\t\t\n\t\t\t\t<div class=\"carousel \">\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/07\/casavolver_02.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/07\/casavolver_03.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/07\/casavolver_05.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/07\/casavolver_04.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"xl:hidden h-8 flex items-center justify-center text-center whitespace-no-wrap pt-3\">\n\t\t\t\t\t<span class=\"image-indicator title-5\"><\/span>\n\t\t\t\t<\/div>\n\n\n\n\t\t\t\t<div class=\"absolute cursor-left hidden\"><\/div>\n\t\t\t\t<div class=\"absolute cursor-right hidden\"><\/div>\n\n\t\t<\/div>\n\n\t  \n\n<\/div>\n\n\n\n\n<p><\/p>\n","protected":false},"featured_media":0,"menu_order":5,"template":"","class_list":["post-1216","naming","type-naming","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/naming\/1216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/naming"}],"about":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/types\/naming"}],"wp:attachment":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/media?parent=1216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}