{"id":2661,"date":"2025-11-26T13:13:11","date_gmt":"2025-11-26T11:13:11","guid":{"rendered":"https:\/\/somosusted.com\/?post_type=naming&#038;p=2661"},"modified":"2025-11-26T13:20:49","modified_gmt":"2025-11-26T11:20:49","slug":"morreig","status":"publish","type":"naming","link":"https:\/\/somosusted.com\/ca\/naming-projects\/morreig\/","title":{"rendered":"Morreig"},"content":{"rendered":"\n<p><em>Morreig<\/em> \u00e9s un local al melic de Gr\u00e0cia on trobar\u00e0s gelats, brioixos i gelats amb brioixos, a m\u00e9s d&#8217;altres peces d&#8217;alta pastisseria, obra del <em>Meilleur Ouvrier de France Boulanger 2019<\/em>, Matthieu Atzenhoffermof. A ell li devem una part de la inspiraci\u00f3 per al nom. <em>Morreig<\/em> \u00e9s la versi\u00f3 catalana de <em>French Kiss<\/em>. L&#8217;altra, la devem a un intens exercici de testing.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1920\" data-id=\"2481\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-02.jpg\" alt=\"\" class=\"wp-image-2481\" srcset=\"https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-02.jpg 1440w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-02-960x1280.jpg 960w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-02-768x1024.jpg 768w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-02-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1920\" data-id=\"2472\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-05.jpg\" alt=\"\" class=\"wp-image-2472\" srcset=\"https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-05.jpg 1440w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-05-960x1280.jpg 960w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-05-768x1024.jpg 768w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-05-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1920\" data-id=\"2478\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-03.jpg\" alt=\"\" class=\"wp-image-2478\" srcset=\"https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-03.jpg 1440w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-03-960x1280.jpg 960w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-03-768x1024.jpg 768w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-03-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1920\" data-id=\"2475\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-04.jpg\" alt=\"\" class=\"wp-image-2475\" srcset=\"https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-04.jpg 1440w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-04-960x1280.jpg 960w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-04-768x1024.jpg 768w, https:\/\/somosusted.com\/wp-content\/uploads\/2025\/10\/usted-morreig-naming-04-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n<\/figure>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","class_list":["post-2661","naming","type-naming","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/naming\/2661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/naming"}],"about":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/types\/naming"}],"wp:attachment":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/media?parent=2661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}