{"id":1162,"date":"2020-06-08T13:46:15","date_gmt":"2020-06-08T11:46:15","guid":{"rendered":"http:\/\/somosusted.com\/project\/prats\/"},"modified":"2020-08-30T09:52:08","modified_gmt":"2020-08-30T07:52:08","slug":"prats","status":"publish","type":"project","link":"https:\/\/somosusted.com\/ca\/project\/prats\/","title":{"rendered":"Prats"},"content":{"rendered":"\n<p>Prats, <em>el major fabricant de lents oft\u00e0lmiques d\u2019Espanya<\/em>, portava treballant des de 1969 per millorar la qualitat del seu producte i fidelitzar el seu canal de distribuci\u00f3. Per\u00f2, qu\u00e8 fas quan la teva compet\u00e8ncia t\u2019est\u00e0 traient quota de mercat gr\u00e0cies a la seva comunicaci\u00f3? Tu nom\u00e9s tens un logotip. Ells tenen una marca. Per aix\u00f2 vam crear <em>\u201cFocusing on you\u201d<\/em>.&nbsp;<\/p>\n\n\n\n<div id=\"gallery-block_5ee87af7d7f95\" class=\"gallery-block w-full\">\n\n    \n\n\t\t<div class=\"cursor-carousel relative\">\n\t\t\t\n\t\t\t\t<div class=\"carousel \">\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_piezas_01.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_piezas_02.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_piezas_04.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_piezas_03.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"xl:hidden h-8 flex items-center justify-center text-center whitespace-no-wrap pt-3\">\n\t\t\t\t\t<span class=\"image-indicator title-5\"><\/span>\n\t\t\t\t<\/div>\n\n\n\n\t\t\t\t<div class=\"absolute cursor-left hidden\"><\/div>\n\t\t\t\t<div class=\"absolute cursor-right hidden\"><\/div>\n\n\t\t<\/div>\n\n\t  \n\n<\/div>\n\n\n\n\n\n\n<div id=\"quote-block_5f030043d28df\" class=\"quote\">\n\n\t<div class=\"lg:flex items-stretch justify-between\">\n    \n    \t<div class=\"text-big mb-8 lg:mb-0 lg:w-2\/3\">\n\n    \t\tPer competir s\u2019ha d\u2019humanitzar la marca i deixar de pensar nom\u00e9s en el producte. <br \/>\r\n\t\t\t\n\t\t\t\n\n    \t<\/div>   \n\n    \t<div class=\"lg:w-1\/4 lg:flex flex-col justify-between lg:text-right \">\n    \t\n\t    \t<div class=\"title-5 line-height\"><\/div>\n\t\t\t\n\t\t\t<div class=\"title-5 line-height text-light-gray xl:text-black\"><\/div>\n\n\t\t<\/div>\n\t\n\t<\/div>\n\n\n\n<\/div>\n\n\n\n\n<figure class=\"wp-block-embed-vimeo wp-block-embed is-type-video is-provider-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Grupo Prats\" src=\"https:\/\/player.vimeo.com\/video\/216544399?dnt=1&amp;app_id=122963\" width=\"600\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Vam desenvolupar tots els seus materials corporatius i una<em> campanya B2B amb incursions cap al B2C<\/em>, gr\u00e0cies a la seva pres\u00e8ncia en \u00f2ptiques. <\/p>\n\n\n\n<figure class=\"wp-block-embed-vimeo wp-block-embed is-type-video is-provider-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Colormatic by Prats\" src=\"https:\/\/player.vimeo.com\/video\/216530614?dnt=1&amp;app_id=122963\" width=\"600\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Un exemple d\u2019aix\u00f2 \u00e9s la transformaci\u00f3 d\u2019un avorrit cat\u00e0leg de lents 100% t\u00e8cnic en una revista de branded content, una manera d\u2019arribar al p\u00fablic final amb un format mai abans utilitzat en el sector. <em>onFocus<\/em> va ser premiada amb un Laus i va ser ressenyada per publicacions com It\u2019s Nice That o The Future Laboratory.&nbsp;<\/p>\n\n\n\n<div id=\"gallery-block_5f2c359fb9db5\" class=\"gallery-block w-full\">\n\n    \n\n\t\t<div class=\"cursor-carousel relative\">\n\t\t\t\n\t\t\t\t<div class=\"carousel \">\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_mag_01.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_mag_02.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_mag_06.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_mag_05.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_mag_03.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/06\/prats_mag_04.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"xl:hidden h-8 flex items-center justify-center text-center whitespace-no-wrap pt-3\">\n\t\t\t\t\t<span class=\"image-indicator title-5\"><\/span>\n\t\t\t\t<\/div>\n\n\n\n\t\t\t\t<div class=\"absolute cursor-left hidden\"><\/div>\n\t\t\t\t<div class=\"absolute cursor-right hidden\"><\/div>\n\n\t\t<\/div>\n\n\t  \n\n<\/div>\n\n","protected":false},"featured_media":1784,"menu_order":34,"template":"","project_type":[21,23,24,27],"class_list":["post-1162","project","type-project","status-publish","has-post-thumbnail","hentry","project_type-branding-ca","project_type-digital-ca","project_type-print-ca","project_type-video-ca"],"acf":[],"_links":{"self":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/project\/1162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/media\/1784"}],"wp:attachment":[{"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/media?parent=1162"}],"wp:term":[{"taxonomy":"project_type","embeddable":true,"href":"https:\/\/somosusted.com\/ca\/wp-json\/wp\/v2\/project_type?post=1162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}