{"id":1127,"date":"2020-07-06T13:34:09","date_gmt":"2020-07-06T11:34:09","guid":{"rendered":"http:\/\/somosusted.com\/project\/ajuntament-de-barcelona\/"},"modified":"2020-08-08T12:42:35","modified_gmt":"2020-08-08T10:42:35","slug":"ajuntament-de-barcelona","status":"publish","type":"project","link":"https:\/\/somosusted.com\/en\/project\/ajuntament-de-barcelona\/","title":{"rendered":"Barcelona City Council"},"content":{"rendered":"\n<p>Yes, it&#8217;s true. <em>Barcelona smells of urine<\/em>; everyone says so. It&#8217;s the heat, the beer and especially the people peeing in the street. Together with Atipus studio we created a campaign for these people with <em>a clear, concise message<\/em>, accompanied by signs indicating the new public toilets the city council had installed for them.&nbsp;<\/p>\n\n\n\n<div id=\"gallery-block_5f16b652fbd55\" class=\"gallery-block w-full\">\n\n    \n\n\t\t<div class=\"cursor-carousel relative\">\n\t\t\t\n\t\t\t\t<div class=\"carousel \">\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/07\/aguanta_imatges_02.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/07\/aguanta_imatges_03.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/07\/aguanta_imatges_05.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/07\/aguanta_imatges_06.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"slide\">\n\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"block\" src=\"https:\/\/somosusted.com\/wp-content\/uploads\/2020\/07\/aguanta_imatges_04.jpg\" alt=\"\">\n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"xl:hidden h-8 flex items-center justify-center text-center whitespace-no-wrap pt-3\">\n\t\t\t\t\t<span class=\"image-indicator title-5\"><\/span>\n\t\t\t\t<\/div>\n\n\n\n\t\t\t\t<div class=\"absolute cursor-left hidden\"><\/div>\n\t\t\t\t<div class=\"absolute cursor-right hidden\"><\/div>\n\n\t\t<\/div>\n\n\t  \n\n<\/div>\n\n\n\n\n<p><\/p>\n","protected":false},"featured_media":967,"menu_order":40,"template":"","project_type":[26],"class_list":["post-1127","project","type-project","status-publish","has-post-thumbnail","hentry","project_type-print-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/project\/1127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/media\/967"}],"wp:attachment":[{"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/media?parent=1127"}],"wp:term":[{"taxonomy":"project_type","embeddable":true,"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/project_type?post=1127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}