{"id":2803,"date":"2026-04-21T17:34:43","date_gmt":"2026-04-21T15:34:43","guid":{"rendered":"https:\/\/somosusted.com\/?post_type=project&#038;p=2803"},"modified":"2026-04-21T17:34:43","modified_gmt":"2026-04-21T15:34:43","slug":"marset","status":"publish","type":"project","link":"https:\/\/somosusted.com\/en\/project\/marset\/","title":{"rendered":"Marset"},"content":{"rendered":"\n<p>Hemos sido responsables de todos los textos de comunicaci\u00f3n de <em>Marset<\/em> a nivel global, en colaboraci\u00f3n con Querida, responsables de la direcci\u00f3n creativa y art\u00edstica de la marca. Una colaboraci\u00f3n que nos ha dado la oportunidad de evolucionar el tono de voz y desarrollar una amplia variedad de contenidos, pero tambi\u00e9n de entrar en contacto con personas que ampliaron nuestra manera de entender y vivir el dise\u00f1o, la luz, el interiorismo y la cultura.<\/p>\n\n\n<div class=\"html\">\n<style>\n  \/* --- ESTILS GENERALS (ORDINADOR) --- *\/\n  .video-container {\n    display: flex;\n    gap: 20px; \/* Separaci\u00f3 lateral en escriptori *\/\n    justify-content: center;\n    width: 100%;\n    align-items: center;\n    box-sizing: border-box; \n  }\n\n  .video-wrapper {\n    flex: 1;\n    max-width: 50%;\n    position: relative;\n  }\n\n  .video-wrapper iframe {\n    width: 100%;\n    aspect-ratio: 4 \/ 5; \/* Format 1080x1350 *\/\n    height: 100%;\n    border: none;\n    border-radius: 0;\n    display: block;\n  }\n\n  \/* --- VERSI\u00d3 M\u00d2BIL --- *\/\n  @media (max-width: 768px) {\n    .video-container {\n      flex-direction: column;\n      gap: 10px; \n      padding-left: 12px;  \n      padding-right: 12px; \n    }\n\n    .video-wrapper {\n      max-width: 100%;\n      width: 100%;\n      flex: none;\n    }\n  }\n<\/style>\n\n<div class=\"video-container\">\n  <div class=\"video-wrapper\">\n    <iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/1177318416?h=c724e1228f&amp;background=1&amp;autoplay=1&amp;loop=1&amp;muted=1&amp;controls=0&amp;title=0&amp;byline=0&amp;portrait=0\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen=\"\" title=\"Video 1\">\n    <\/iframe>\n  <\/div>\n\n  <div class=\"video-wrapper\">\n    <iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/1177319099?h=2886ae5268&amp;background=1&amp;autoplay=1&amp;loop=1&amp;muted=1&amp;controls=0&amp;title=0&amp;byline=0&amp;portrait=0\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen=\"\" title=\"Video 2\">\n    <\/iframe>\n  <\/div>\n<\/div>\n<\/div>\n\n\n<p>En 2025 creamos la idea y desarrollamos el libro de marca &#8220;Anatom\u00eda de la Luz&#8221;, que disecciona el concepto de luz desde todos los \u00e1ngulos a trav\u00e9s de la participaci\u00f3n de diferentes personalidades vinculadas al dise\u00f1o, la oftalmolog\u00eda, el arte, la arquitectura, la psicolog\u00eda y el pensamiento. Un hito en la historia de Marset.<\/p>\n\n\n<div class=\"html\">\n<style>\n  \/* --- ESTILS GENERALS (ORDINADOR) --- *\/\n  .video-container {\n    display: flex;\n    gap: 20px; \/* Separaci\u00f3 lateral en escriptori *\/\n    justify-content: center;\n    width: 100%;\n    align-items: center;\n    box-sizing: border-box; \n  }\n\n  .video-wrapper {\n    flex: 1;\n    max-width: 50%;\n    position: relative;\n  }\n\n  .video-wrapper iframe {\n    width: 100%;\n    aspect-ratio: 4 \/ 5; \/* Format 1080x1350 *\/\n    height: 100%;\n    border: none;\n    border-radius: 0;\n    display: block;\n  }\n\n  \/* --- VERSI\u00d3 M\u00d2BIL --- *\/\n  @media (max-width: 768px) {\n    .video-container {\n      flex-direction: column;\n      \n      \/* HE REDU\u00cfT AIX\u00d2 DE 30px A 10px: *\/\n      gap: 10px; \n      \n      \/* Marge lateral (ajustat al teu site) *\/\n      padding-left: 12px;  \n      padding-right: 12px; \n    }\n\n    .video-wrapper {\n      max-width: 100%;\n      width: 100%;\n      flex: none;\n    }\n  }\n<\/style>\n\n<div class=\"video-container\">\n  <div class=\"video-wrapper\">\n    <iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/1177363417?h=28c9f83df0&amp;background=1&amp;autoplay=1&amp;loop=1&amp;muted=1&amp;controls=0&amp;title=0&amp;byline=0&amp;portrait=0\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen=\"\" title=\"Video 1\">\n    <\/iframe>\n  <\/div>\n\n  <div class=\"video-wrapper\">\n    <iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/1177363368?h=ff66ab718e&amp;background=1&amp;autoplay=1&amp;loop=1&amp;muted=1&amp;controls=0&amp;title=0&amp;byline=0&amp;portrait=0\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen=\"\" title=\"Video 2\">\n    <\/iframe>\n  <\/div>\n<\/div>\n<\/div>\n\n\n<p>Hemos entrevistado a personajes como <em>James Rhodes<\/em>, <em>Greta Fern\u00e1ndez<\/em> o el equipo de <em>Tiberi<\/em>. Preparado y estructurado charlas como el di\u00e1logo entre el dise\u00f1ador <em>Jordi Canudas<\/em> y el artista <em>Barquero<\/em> para presentar los nuevos colores de Dipping Light. O creado conceptos para instalaciones del estudio de arquitectura <em>Mesura<\/em>. La variedad de proyectos realizados para la marca es ampl\u00edsima, y cada uno de ellos ha representado un reto interesante y una responsabilidad que ha sido un honor aceptar. Colaborar con <em>Marset<\/em> nos ha permitido explorar y avanzar junto a la marca, y nos ha hecho crecer profesional y personalmente.<\/p>\n","protected":false},"featured_media":2795,"menu_order":8,"template":"","project_type":[22],"class_list":["post-2803","project","type-project","status-publish","has-post-thumbnail","hentry","project_type-branding-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/project\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/media\/2795"}],"wp:attachment":[{"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/media?parent=2803"}],"wp:term":[{"taxonomy":"project_type","embeddable":true,"href":"https:\/\/somosusted.com\/en\/wp-json\/wp\/v2\/project_type?post=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}